{"id":4621,"date":"2019-03-22T11:48:55","date_gmt":"2019-03-22T09:48:55","guid":{"rendered":"https:\/\/www.raiels.cat\/?p=4621"},"modified":"2019-05-10T13:39:06","modified_gmt":"2019-05-10T11:39:06","slug":"entrega-placas-slow-food-km0-2019","status":"publish","type":"post","link":"https:\/\/www.raiels.cat\/es\/entrega-placas-slow-food-km0-2019\/","title":{"rendered":"\u00c9xito de asistencia al acto de entrega de caracoles Slow Food km0  en l\u2019Ametlla de Mar"},"content":{"rendered":"<p>Este 18 de marzo la Ametlla de Marsse ha vestido de fiesta para acoger el acto anual de la <strong>Entrega del placas\u00a0 Km0-Slow Food a restaurantes y comedores escolares<\/strong> (<strong>descargar programa de la jornada<\/strong>), al qual Raiels hemos dado apoyo <a href=\"https:\/\/www.raiels.cat\/projecte\/secretaria-tecnica-slow-food-catalunya-km0\/\">como Secretar\u00eda T\u00e9cnica del grupo Slow Food-Km0<\/a>. Una gran carpa situada en el Muelle Pesquero (La Cala) ha sido el escenario de una fiesta ya consolidada que, tras 10 a\u00f1os de su celebraci\u00f3n, impulsa el grupo de cocineras y cocineros que apuestan de manera firme por la cultura del bueno, limpio y justo.<\/p>\n<p>Desde las 10 de la ma\u00f1ana y hasta las 2 de la tarde el <strong>Mercado de la Tierra<\/strong> se ha convertido en un espacio para el conocimiento de peque\u00f1os productores y elaboradores de toda Catalu\u00f1a que siguen tambi\u00e9n la filosof\u00eda del bueno, limpio y justo; muchos de ellos ecol\u00f3gicos. Durante este mercado, las personas asistentes han podido conocer de primera mano m\u00e1s de una cincuentena de peque\u00f1os e interesantes proyectos, as\u00ed como tambi\u00e9n degustar sus productos, a trav\u00e9s de catas proporcionados por los mismos productores.<\/p>\n<p>Otras actividades paralelas han complementado la actividad de ma\u00f1ana: una <strong>conferencia sobre Pesca Sostenible<\/strong> a cargo del Director General de Pesca, Sr. Sergi Tudela; y la <strong>presentaci\u00f3n del libro \u00abLa Cuina Tradicional de la Cala\u00bb<\/strong>, de M. Teresa Nolla y Gabriel Comes; ambos actos muy concurridos tanto por el colectivo de\u00a0 cocineras y cocineros como para gente de la Ametlla de Mar. A continuaci\u00f3n, se ha realizado\u00a0 la <strong>reuni\u00f3n de cocineras y cocineros, <\/strong>en que se han expuesto las principales actividades realizadas durante este a\u00f1o, as\u00ed como las previsiones de futuro.<\/p>\n<p>El <strong>\u00abTast Km0\u00bb,<\/strong> almuerzo dise\u00f1ado y preparado por los 7 restaurantes del convivium Slow Food Tarraco, ha sido otro de los momentos estrella de la jornada, en que unas 250 personas asistentes han podido degustar la cocina de tierras tarraconenses basada en criterios del bueno, limpio y justo; con m\u00fasica ambiente de Paco en la Luna. Un showcooking de postres de la Ametlla de Mar a cargo de Gessam\u00ed Caram\u00e9s ha acompa\u00f1ado durante la sobremesa.<\/p>\n<p>El acto m\u00e1s esperado de la jornada, la Entrega de Placas, conducido por Ruth Troyano y Jos\u00e9 Sucarrats, se ha iniciado con la <strong>entrega de los premios a productores comprometidos<\/strong>, reconocimiento que otorgan los propios cocineras y cocineros a aquellas iniciativas que se consideran relevantes por su implicaci\u00f3n en los valores del bueno, limpio y justo. Los proyectos reconocidos con esta categor\u00eda han sido<strong>: <\/strong><a href=\"http:\/\/www.espigall.cat\/\"><strong>L\u2019Espigall<\/strong><\/a><strong>, <\/strong><a href=\"http:\/\/www.boletbenfet.com\/\"><strong>Bolet Ben Fet<\/strong><\/a><strong>, <\/strong><a href=\"https:\/\/www.escairador.com\/ca\/\"><strong>l\u2019Escairador,<\/strong><\/a> <a href=\"http:\/\/www.senglardegirona.com\/\"><strong>Senglar de Girona<\/strong><\/a><strong>, <\/strong><a href=\"https:\/\/www.pasturem.cat\/product-page\/la-segalla\"><strong>la Segalla<\/strong><\/a><strong> i <\/strong><a href=\"http:\/\/tofonadelaconca.com\/\"><strong>T\u00f2fona de la Conca<\/strong><\/a><strong>.<\/strong> Un reconocimiento que ha sido muy valorado por parte de todos los productores que lo han recibido y que les anima a continuar trabajando en su proyecto, a pesar de los retos que a menudo deben afrontar.<\/p>\n<p>A continuaci\u00f3n, se han entregado los premios a las cocineras y cocineros Km0. En total, <strong>51 cocineras y cocineros de restaurantes y 8 de comedores escolares recibieron el distintivo<\/strong>, este a\u00f1o representado por una nueva placa de hierro que incorpora el logotipo de la Comunidad de Cocineras y Cocineros Slow Food de Catalu\u00f1a, recientemente creada. Este a\u00f1o son <strong>11 los nuevos restaurantes que se incorporan a este proyecto, as\u00ed como tambi\u00e9n 7 nuevos comedores escolares <\/strong>(gestionados por <a href=\"http:\/\/ecomenja.com\/\">Ecomenja<\/a>) que se suman a la \u00fanica escuela que hasta ahora contaba con este reconocimiento. As\u00ed, los comedores escolares es un nuevo proyecto que comienza a crecer en la familia del bueno, limpio y justo, pero en el \u00e1mbito de la educaci\u00f3n alimentaria, en las escuelas.<\/p>\n<p>Finalmente, se ha entregado tambi\u00e9n una placa al alcalde de l&#8217;Ametlla de Mar, en Sr. Jordi Gaseni, como muestra de agradecimiento por la implicaci\u00f3n que tanto el <a href=\"https:\/\/www.ametllamar.cat\/ajuntament\/\">Ayuntamiento de la Ametlla de Mar<\/a> como su ciudadan\u00eda han tenido en la organizaci\u00f3n del acto<\/p>\n<p><strong>\u00a0<\/strong><em>Un a\u00f1o m\u00e1s, el proyecto Slow food-Km0 crece, se consolida y se da a conocer en el territorio. La jornada de entrega de placas es siempre un punto de encuentro entre cocineras y cocineros, productores y productoras y otras personas afines proyecto, que ayuda a hacer red en el seno de una jornada festiva y de celebraci\u00f3n. Un punto de inflexi\u00f3n que anima y da fuerzas a todas las personas que participan a continuar trabajando de manera coordinada por el bueno, limpio y justo. Este a\u00f1o, adem\u00e1s, la implicaci\u00f3n y participaci\u00f3n de la poblaci\u00f3n donde se ha llevado a cabo ha sido tambi\u00e9n un elemento que ha dado fuerza y \u200b\u200bvalor a\u00f1adido al acto, siendo una muestra real de un proyecto gestado e impulsado con la participaci\u00f3n e implicaci\u00f3n de todos!<\/em>\u00a0<strong>Muchas gracias a todas aquellas personas que lo han hecho posible!!!<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Para m\u00e1s informaci\u00f3n consultar la <a href=\"https:\/\/www.km0slowfood.com\/?lang=es\">p\u00e0gina web del proyecto Slow Food-Km0.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 18 de marzo la Ametlla de Marsse ha vestido de fiesta para acoger el acto anual de la Entrega del placas\u00a0 Km0-Slow Food a restaurantes<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":4625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-4621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/posts\/4621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/comments?post=4621"}],"version-history":[{"count":2,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/posts\/4621\/revisions"}],"predecessor-version":[{"id":4660,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/posts\/4621\/revisions\/4660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/media\/4625"}],"wp:attachment":[{"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/media?parent=4621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/categories?post=4621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.raiels.cat\/es\/wp-json\/wp\/v2\/tags?post=4621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}